{"id":6852,"date":"2013-10-31T15:27:40","date_gmt":"2013-10-31T14:27:40","guid":{"rendered":"https:\/\/www.arteco-global.com\/it\/?p=6852"},"modified":"2020-07-01T12:00:20","modified_gmt":"2020-07-01T10:00:20","slug":"italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite","status":"publish","type":"post","link":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/","title":{"rendered":"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile"},"content":{"rendered":"<p>Il server di supervisione HSYCO permette di gestire le funzioni di building &#038; home automation tramite\u00a0un\u2019interfaccia grafica web based, completamente personalizzabile, che pu\u00f2 essere utilizzata in locale\u00a0e da remoto da iPhone, iPad, tablet e telefoni Android, personal computer o display touch.<\/p>\n<p>L\u2019integrazione con i controller IP Arteco Everywhere consente di creare con semplicit\u00e0 e molto\u00a0rapidamente applicazioni web based con interfaccia grafica evoluta.<\/p>\n<p>Arteco Everywhere \u00e8 un modulo input-output Ethernet digitale che\u00a0consente di controllare i dispositivi di campo, L\u2019integrazione con\u00a0HSYCO consente di creare in modo semplice ed espandibile\u00a0applicazioni sofisticate con interfaccia grafica evoluta per il\u00a0controllo di ingressi e uscite.<\/p>\n<p>HSYCO consente di allargare gli orizzonti della videosorveglianza,\u00a0grazie all\u2019integrazione nativa tramite protocollo con i sistemi di\u00a0antintrusione, controllo accessi e con i dispositivi di campo.<\/p>\n<p>Arteco Everywhere \u00e8 lo strumento ideale per integrare luci,\u00a0automazioni, sistemi clima quando non sia presente un\u2019architettura a bus per il controllo. Si\u00a0presta ad ogni ambito installativo e risulta di facile configurazione. Con un semplice\u00a0collegamento di rete la gestione di due o pi\u00f9 moduli Everywhere diventa immediata e\u00a0consente di controllare un numero di dispositivi illimitato.<\/p>\n<p>E\u2019 disponibile in due versioni, il modulo a 4 input e 4 output, e il modulo a 8 input e 8\u00a0output. Gli ingressi sono optoisolati e le uscite sono del tipo a rel\u00e8.<\/p>\n<h3>L\u2019integrazione &#8211; Esempi Applicativi<\/h3>\n<p>L\u2019integrazione dei moduli Arteco Everywhere con HSYCO consente di realizzare\u00a0applicazioni molto interessanti per il settore sicurezza e videosorveglianza. HSYCO, infatti,\u00a0integra nativamente le centrali anti intrusione dei principali produttori ed \u00e8 in grado di\u00a0visualizzare lo stato completo dell\u2019impianto e degli allarmi. Utilizzando i moduli Arteco\u00a0Everywhere, pu\u00f2 controllare luci e automazioni, ad esempio accendendo le luci in caso di\u00a0ingresso autorizzato o attivando scenari di simulazione di presenza in caso contrario. Inoltre,\u00a0HSYCO \u00e8 in grado di visualizzare le immagini live e le registrazioni delle telecamere di\u00a0sorveglianza. Il sistema di videosorveglianza e antintrusione cos\u00ec configurato pu\u00f2 essere\u00a0controllato localmente e a distanza.<\/p>\n<p>Nell\u2019 ambito\u00a0dell\u2019 automazione\u00a0industriale, HSYCO\u00a0SCHEDULER \u00e8 una\u00a0sofisticata funzionalit\u00e0 di\u00a0programmazione e\u00a0coordinamento del funzionamento dei sistemi\u00a0di campo.<\/p>\n<p>HSYCO \u00e8 in grado di inviare e-mail, sms, messaggi vocali per informare sullo stato degli\u00a0impianti e per notificare allarmi.<\/p>\n<p>HSYCO WIRING EDITOR fornisce\u00a0un\u2019interfaccia Web semplice e\u00a0intuitiva per la creazione di\u00a0\u201cconnessioni\u201d virtuali tra datapoint\u00a0di input e uscita e per la creazione\u00a0di scenari. HSYCO genera\u00a0automaticamente l\u2019interfaccia di\u00a0configurazione per gli ingressi e le\u00a0uscite di Arteco Everywhere\u00a0permettendo di creare velocemente\u00a0e in modo molto s emplice\u00a0associazioni logiche o scenari pi\u00f9\u00a0complessi.<\/p>\n<h2><a href=\"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/Arteco-v3.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica la documentazione in pdf<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Il server di supervisione HSYCO permette di gestire le funzioni [&hellip;]<\/p>\n","protected":false},"author":4424,"featured_media":6854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,50,51],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco\" \/>\n<meta property=\"og:description\" content=\"Il server di supervisione HSYCO permette di gestire le funzioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/\" \/>\n<meta property=\"og:site_name\" content=\"Arteco\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-31T14:27:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-01T10:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marketing Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/\",\"url\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/\",\"name\":\"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco\",\"isPartOf\":{\"@id\":\"https:\/\/www.arteco-global.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png\",\"datePublished\":\"2013-10-31T14:27:40+00:00\",\"dateModified\":\"2020-07-01T10:00:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/0d70c817ac0006e81e713693d21699ae\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage\",\"url\":\"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png\",\"contentUrl\":\"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png\",\"width\":660,\"height\":371},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.arteco-global.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/#website\",\"url\":\"https:\/\/www.arteco-global.com\/en\/\",\"name\":\"Arteco\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arteco-global.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/0d70c817ac0006e81e713693d21699ae\",\"name\":\"Marketing Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e729644e5ce92cb627600a4b2503e259?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e729644e5ce92cb627600a4b2503e259?s=96&d=mm&r=g\",\"caption\":\"Marketing Marketing\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/","og_locale":"en_US","og_type":"article","og_title":"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco","og_description":"Il server di supervisione HSYCO permette di gestire le funzioni [&hellip;]","og_url":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/","og_site_name":"Arteco","article_published_time":"2013-10-31T14:27:40+00:00","article_modified_time":"2020-07-01T10:00:20+00:00","og_image":[{"width":660,"height":371,"url":"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png","type":"image\/png"}],"author":"Marketing Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marketing Marketing","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/","url":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/","name":"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile - Arteco","isPartOf":{"@id":"https:\/\/www.arteco-global.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage"},"image":{"@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png","datePublished":"2013-10-31T14:27:40+00:00","dateModified":"2020-07-01T10:00:20+00:00","author":{"@id":"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/0d70c817ac0006e81e713693d21699ae"},"breadcrumb":{"@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#primaryimage","url":"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png","contentUrl":"https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png","width":660,"height":371},{"@type":"BreadcrumbList","@id":"https:\/\/www.arteco-global.com\/en\/2013\/italiano-hsyco-e-arteco-everywhere-la-soluzione-semplice-potente-ed-espandibile-per-il-controllo-di-ingressi-e-uscite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arteco-global.com\/en\/"},{"@type":"ListItem","position":2,"name":"HSYCO e ARTECO EVERYWHERE: la soluzione semplice, potente ed espandibile"}]},{"@type":"WebSite","@id":"https:\/\/www.arteco-global.com\/en\/#website","url":"https:\/\/www.arteco-global.com\/en\/","name":"Arteco","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arteco-global.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/0d70c817ac0006e81e713693d21699ae","name":"Marketing Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arteco-global.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e729644e5ce92cb627600a4b2503e259?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e729644e5ce92cb627600a4b2503e259?s=96&d=mm&r=g","caption":"Marketing Marketing"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"thumbnail":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE-320x180.png",320,180,true],"medium":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"medium_large":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"large":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"1536x1536":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"2048x2048":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"post-immagine-evidenza-inglese-thumbnail":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",660,371,false],"logo-distributore":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE.png",107,60,false],"post-thumbnail":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE-150x150.png",150,150,true],"CCNZMarkerImage":["https:\/\/www.arteco-global.com\/wp-content\/uploads\/2013\/10\/HSYCO-E-ARTECO-EVERYWHERE-32x32.png",32,32,true]},"uagb_author_info":{"display_name":"Marketing Marketing","author_link":"https:\/\/www.arteco-global.com\/en\/author\/marketing-marketing\/"},"uagb_comment_info":14,"uagb_excerpt":"Il server di supervisione HSYCO permette di gestire le funzioni [&hellip;]","_links":{"self":[{"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/posts\/6852"}],"collection":[{"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/users\/4424"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/comments?post=6852"}],"version-history":[{"count":1,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/posts\/6852\/revisions"}],"predecessor-version":[{"id":19466,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/posts\/6852\/revisions\/19466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/media\/6854"}],"wp:attachment":[{"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/media?parent=6852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/categories?post=6852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arteco-global.com\/en\/wp-json\/wp\/v2\/tags?post=6852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}